{"id":23957,"date":"2021-03-15T19:16:04","date_gmt":"2021-03-15T18:16:04","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/03\/15\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\/"},"modified":"2025-12-15T12:55:24","modified_gmt":"2025-12-15T11:55:24","slug":"arbitrage-par-videoconference-contre-la-volonte-dune-partie","status":"publish","type":"post","link":"https:\/\/swisstrans.info\/fr\/2021\/03\/15\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\/","title":{"rendered":"Arbitrage par vid\u00e9oconf\u00e9rence contre la volont\u00e9 d&rsquo;une partie"},"content":{"rendered":"<p>Juste en p\u00e9riode de Corona, la question se pose \u00e9galement en cas de litiges dans le domaine de la logistique et du transport : comment obtenir rapidement une d\u00e9cision sur le litige ? Les tribunaux d&rsquo;arbitrage sont une alternative \u00e0 la justice \u00e9tatique et peuvent se distinguer par une conception proc\u00e9durale particuli\u00e8rement flexible.<\/p>\n<p style=\"text-align: center\">par Thorsten Vogl<\/p>\n<p>(Zurich) Cet avantage, particuli\u00e8rement pertinent dans la situation actuelle qui rend les voyages et les r\u00e9unions impossibles, a \u00e9t\u00e9 renforc\u00e9 par une d\u00e9cision de la Cour supr\u00eame autrichienne, qui a permis \u00e0 un tribunal d&rsquo;arbitrage d&rsquo;ordonner une audience par vid\u00e9oconf\u00e9rence, m\u00eame si une partie s&rsquo;y oppose (Cour supr\u00eame de la R\u00e9publique d&rsquo;Autriche, d\u00e9cision du 23 juillet 2020, n\u00b0 18 ONc 3\/20s). En d\u00e9tail : en janvier 2020, le tribunal d&rsquo;arbitrage avait convoqu\u00e9 une audience (pr\u00e9sentielle) pour le 15 avril 2020 dans le cadre d&rsquo;une proc\u00e9dure d&rsquo;arbitrage en cours depuis ao\u00fbt 2017.<\/p>\n<h5><strong>D\u00e9but de l&rsquo;audience ajust\u00e9 au d\u00e9calage horaire<\/strong><\/h5>\n<p>En raison de la pand\u00e9mie de Corona et apr\u00e8s avoir entendu les parties, il a d\u00e9cid\u00e9 le 8 avril 2020 qu&rsquo;au lieu de l&rsquo;audience en pr\u00e9sentiel, une vid\u00e9oconf\u00e9rence serait tenue. Comme le t\u00e9moin \u00e0 entendre r\u00e9sidait \u00e0 Los Angeles, il a d\u00e9plac\u00e9 le d\u00e9but de l&rsquo;audience (initialement pr\u00e9vu \u00e0 10h00) \u00e0 15h00 CET, ce qui signifiait pour le t\u00e9moin un d\u00e9but \u00e0 6h00 du matin. Les d\u00e9fendeurs en arbitrage s&rsquo;\u00e9taient oppos\u00e9s \u00e0 la vid\u00e9oconf\u00e9rence : ils estimaient qu&rsquo;en raison du changement de date tr\u00e8s court, ils n&rsquo;avaient pas suffisamment de temps pour se pr\u00e9parer. Un d\u00e9but \u00e0 6h00 pour le repr\u00e9sentant bas\u00e9 \u00e0 Los Angeles \u00e9tait consid\u00e9r\u00e9 comme vexatoire. De plus, le t\u00e9moin pouvait \u00eatre influenc\u00e9 : on ne pouvait pas v\u00e9rifier si d&rsquo;autres personnes se trouvaient dans la pi\u00e8ce, on ne savait pas quels documents le t\u00e9moin utilisait ; de plus, il pouvait recevoir des messages de chat sans \u00eatre remarqu\u00e9. Le tribunal d&rsquo;arbitrage \u00e9tait donc partial, car il avait viol\u00e9 le principe du traitement \u00e9quitable des parties et n&rsquo;avait pas pris de mesures contre l&rsquo;influence abusive des t\u00e9moins. De plus, ils justifiaient leur demande de r\u00e9cusation en affirmant qu&rsquo;un des trois arbitres avait roul\u00e9 des yeux pendant les d\u00e9clarations de l&rsquo;avocate des d\u00e9fendeurs lors de l&rsquo;audience du 15 avril 2020, lorsque la question de la partialit\u00e9 a \u00e9t\u00e9 discut\u00e9e. La Cour supr\u00eame a rejet\u00e9 la demande de r\u00e9cusation avec des arguments pertinents : - L&rsquo;audience avait \u00e9t\u00e9 fix\u00e9e longtemps \u00e0 l&rsquo;avance ; les d\u00e9fendeurs en arbitrage avaient donc eu suffisamment de temps pour se pr\u00e9parer.<\/p>\n<h5><strong>Pr\u00e9paration non entrav\u00e9e<\/strong><\/h5>\n<p>Le fait qu&rsquo;un changement de date ait eu lieu \u00e0 court terme ne les a donc pas emp\u00each\u00e9s de se pr\u00e9parer. Le rejet d&rsquo;une demande de report ne justifie pas la crainte de partialit\u00e9. Il est dans la nature des choses que celui qui fait une telle demande ait un plus grand int\u00e9r\u00eat \u00e0 la suspension que l&rsquo;autre partie. Cependant, cela ne cr\u00e9e pas de d\u00e9s\u00e9quilibre en cas de rejet de la demande, d&rsquo;autant plus que les d\u00e9fendeurs en arbitrage n&rsquo;avaient pas justifi\u00e9 de mani\u00e8re substantielle l&#8217;emp\u00eachement du t\u00e9moin, mais avaient simplement fait r\u00e9f\u00e9rence de mani\u00e8re g\u00e9n\u00e9rale \u00e0 sa charge de travail dans le cadre du report d&rsquo;\u00e9v\u00e9nements culturels en raison de la pand\u00e9mie de COVID. Dans ce contexte, il convient \u00e9galement de noter que le d\u00e9but pr\u00e9coce de l&rsquo;audience \u00e9tait avantageux, car le t\u00e9moin pouvait ainsi d\u00e9j\u00e0 se consacrer \u00e0 son travail au cours de la matin\u00e9e. 2 - L&rsquo;heure de d\u00e9but pr\u00e9coce ne peut \u00e9galement pas \u00eatre consid\u00e9r\u00e9e comme un traitement injuste, car en raison du d\u00e9calage horaire, l&rsquo;audience devait n\u00e9cessairement avoir lieu en dehors des heures de bureau pour l&rsquo;une des parties. De plus, il convient de souligner l&rsquo;avantage qu&rsquo;il n&rsquo;est pas n\u00e9cessaire de faire un voyage p\u00e9nible, long et co\u00fbteux de Los Angeles \u00e0 Vienne. - L&rsquo;utilisation de la technologie de vid\u00e9oconf\u00e9rence est, comme le tribunal le souligne en se r\u00e9f\u00e9rant \u00e0 la litt\u00e9rature et \u00e0 la jurisprudence, (en Autriche) largement r\u00e9pandue, ce qui a \u00e9galement un impact sur le droit de l&rsquo;arbitrage. La pand\u00e9mie de COVID-19 a encore \u00e9largi le champ d&rsquo;application des vid\u00e9oconf\u00e9rences.<\/p>\n<h5><strong>Technologie de vid\u00e9oconf\u00e9rence reconnue mondialement<\/strong><\/h5>\n<p>Comme le tribunal a utilis\u00e9 WebEx, une technologie de vid\u00e9oconf\u00e9rence reconnue et largement utilis\u00e9e dans le monde entier, il n&rsquo;y a pas eu de violation de l&rsquo;article 6 de la CEDH, car cette disposition garantit non seulement le droit \u00e0 une audience \u00e9quitable, mais aussi le droit \u00e0 l&rsquo;acc\u00e8s \u00e0 la justice, ce qui est \u00e9galement li\u00e9 au droit \u00e0 une protection judiciaire efficace. Les vid\u00e9oconf\u00e9rences entra\u00eenent des \u00e9conomies de co\u00fbts et de temps, favorisant ainsi l&rsquo;application du droit tout en pr\u00e9servant le droit \u00e0 une audience \u00e9quitable. Cela est particuli\u00e8rement vrai en cas de risque d&rsquo;arr\u00eat de la justice. De plus, l&rsquo;influence sur le t\u00e9moin, que les d\u00e9fendeurs en arbitrage ont soulev\u00e9e, ne peut pas \u00eatre compl\u00e8tement exclue m\u00eame lors d&rsquo;audiences en pr\u00e9sentiel, que ce soit par la technologie moderne ou par des accords traditionnels et des informations pr\u00e9alables au t\u00e9moin. Les vid\u00e9oconf\u00e9rences offrent en outre des possibilit\u00e9s de contr\u00f4le efficaces : observation frontale et rapproch\u00e9e, enregistrement de l&rsquo;audition, regard direct dans la cam\u00e9ra pour \u00e9viter de lire des messages de chat sur l&rsquo;\u00e9cran, possibilit\u00e9 pour le t\u00e9moin de faire pivoter la cam\u00e9ra pour montrer la pi\u00e8ce et ses mains \u00e9tant toujours visibles.<\/p>\n<p>Apr\u00e8s tout cela, l&rsquo;ordonnance d&rsquo;une vid\u00e9oconf\u00e9rence, m\u00eame contre la volont\u00e9 d&rsquo;une partie, ne peut pas justifier la crainte de partialit\u00e9 du tribunal d&rsquo;arbitrage. - En ce qui concerne les expressions faciales de l&rsquo;un des trois arbitres, le tribunal a not\u00e9 que m\u00eame si l&rsquo;on interpr\u00e8te le roulement des yeux comme un d\u00e9saccord avec les d\u00e9clarations de l&rsquo;avocat, cela ne signifie pas qu&rsquo;il ne d\u00e9cidera pas objectivement sur le litige. - Une vue d&rsquo;ensemble des circonstances individuelles mentionn\u00e9es pr\u00e9c\u00e9demment ne conduit pas non plus \u00e0 susciter la crainte que le tribunal ne d\u00e9cide pas objectivement. Commentaire La d\u00e9cision de l&rsquo;OGH autrichien offre une ligne directrice fiable pour l&rsquo;ordonnance de vid\u00e9oconf\u00e9rences par les tribunaux d&rsquo;arbitrage, y compris en ce qui concerne la gestion des diff\u00e9rents fuseaux horaires et les strat\u00e9gies pour \u00e9viter l&rsquo;influence sur les t\u00e9moins.<\/p>\n<h5><strong>La vid\u00e9oconf\u00e9rence ne viole pas le droit \u00e0 une audience \u00e9quitable<\/strong><\/h5>\n<p>Il est \u00e9tabli que l&rsquo;ordonnance d&rsquo;une vid\u00e9oconf\u00e9rence, m\u00eame contre la volont\u00e9 d&rsquo;une partie, ne viole ni le droit \u00e0 une audience \u00e9quitable ni le droit \u00e0 un proc\u00e8s \u00e9quitable, de sorte que la tenue d&rsquo;une telle audience ne peut pas entra\u00eener l&rsquo;annulation de la sentence arbitrale ni la r\u00e9cusation des arbitres. Le fait que l&rsquo;OGH souligne les \u00e9conomies de co\u00fbts r\u00e9alis\u00e9es gr\u00e2ce aux vid\u00e9oconf\u00e9rences (pas de frais de voyage, pas d&rsquo;indemnit\u00e9s de pr\u00e9sence, etc.) est particuli\u00e8rement int\u00e9ressant pour les PME : pour elles, il s&rsquo;agit souvent de valeurs de litige plus faibles. Les proc\u00e9dures d&rsquo;arbitrage \u00ab classiques \u00bb avec leurs co\u00fbts abondants sont donc particuli\u00e8rement inadapt\u00e9es \u00e0 ce groupe. Pour proposer une offre int\u00e9ressante \u00e0 ce groupe, qui joue jusqu&rsquo;\u00e0 pr\u00e9sent un r\u00f4le faible dans le domaine de l&rsquo;arbitrage, il est absolument n\u00e9cessaire de miser sur de tels facteurs \u00ab d&rsquo;att\u00e9nuation des co\u00fbts \u00bb. \u00c0 cet \u00e9gard, la SGO \u2013 Organisation permanente suisse d&rsquo;arbitrage \u2013 est un pionnier. Elle a \u00e9t\u00e9 fond\u00e9e par M. le Prof. Dr. Dr. Hans Giger, sp\u00e9cifiquement ax\u00e9e sur les PME.<\/p>\n<p>De plus, on peut s&rsquo;attendre \u00e0 une importance croissante des vid\u00e9oconf\u00e9rences dans le cadre des proc\u00e9dures d&rsquo;arbitrage. Ainsi, la CCI a int\u00e9gr\u00e9 dans ses nouvelles r\u00e8gles d&rsquo;arbitrage, entr\u00e9es en vigueur le 01.01.2021, la possibilit\u00e9 pour le tribunal d&rsquo;arbitrage de pr\u00e9voir des vid\u00e9oconf\u00e9rences (voir art. 26, al. 1). Si ces r\u00e8gles ont donc \u00e9t\u00e9 convenues, on peut supposer un accord des parties pour la tenue de vid\u00e9oconf\u00e9rences. 3 Il convient \u00e9galement de noter que le Conseil international pour l&rsquo;arbitrage commercial a lanc\u00e9 un projet de recherche intitul\u00e9 \u00ab Existe-t-il un droit \u00e0 une audience physique ? \u00bb ; le r\u00e9sultat de l&rsquo;enqu\u00eate devrait \u00eatre int\u00e9ressant !<br \/>\n<a href=\"https:\/\/www.arbitration-icca.org\/introducing-does-right-physical-hearing-exist-international-arbitration-and-calling-contributions\">https:\/\/www.arbitration-icca.org\/introducing-does-right-physical-hearing-exist-international-arbitration-and-calling-contributions<\/a><\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><strong><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-9902 alignleft\" src=\"https:\/\/swisstrans.dashboard.brand-architecture.at\/wp-content\/uploads\/sites\/8\/2025\/12\/Thorsten_Vogl_4.9.20.jpg\" alt=\"\" width=\"153\" height=\"162\" \/>Thorsten Vogl. Ass.iur - Associ\u00e9<\/strong><strong><br \/>\n<\/strong>Membre du conseil d&rsquo;administration de l&rsquo;Organisation permanente suisse d&rsquo;arbitrage (SGO) \u00e0 Zurich. Membre d&rsquo;honneur de l&rsquo;Association pour l&rsquo;unification du droit en Afrique (UNIDA), Paris. R\u00e9dacteur en chef de la <em>Revue de la circulation routi\u00e8re.<\/em> Sp\u00e9cialit\u00e9 en droit du transport et en droit de la cha\u00eene d&rsquo;approvisionnement. <a href=\"https:\/\/www.gsl-group.ch\/de\">https:\/\/www.gsl-group.ch\/de<\/a><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Juste en p\u00e9riode de Corona, la question se pose \u00e9galement en cas de litiges dans le domaine de la logistique et du transport : comment obtenir<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6731,6364,6370,6367],"tags":[],"class_list":["post-23957","post","type-post","status-publish","format-standard","hentry","category-expedition-de-fret-et-logistique","category-schweiz","category-suisse","category-switzerland"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arbitrage par vid\u00e9oconf\u00e9rence contre la volont\u00e9 d&#039;une partie - Swisstrans.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swisstrans.info\/fr\/2021\/03\/15\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arbitrage par vid\u00e9oconf\u00e9rence contre la volont\u00e9 d&#039;une partie - Swisstrans.\" \/>\n<meta property=\"og:description\" content=\"Juste en p\u00e9riode de Corona, la question se pose \u00e9galement en cas de litiges dans le domaine de la logistique et du transport : comment obtenir [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swisstrans.info\/fr\/2021\/03\/15\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\/\" \/>\n<meta property=\"og:site_name\" content=\"Swisstrans\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-15T18:16:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:55:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/swisstrans.dashboard.brand-architecture.at\/wp-content\/uploads\/sites\/8\/2025\/12\/Thorsten_Vogl_4.9.20.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2021\\\/03\\\/15\\\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2021\\\/03\\\/15\\\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Arbitrage par vid\u00e9oconf\u00e9rence contre la volont\u00e9 d&rsquo;une partie\",\"datePublished\":\"2021-03-15T18:16:04+00:00\",\"dateModified\":\"2025-12-15T11:55:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2021\\\/03\\\/15\\\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\\\/\"},\"wordCount\":1587,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2021\\\/03\\\/15\\\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/swisstrans.dashboard.brand-architecture.at\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/12\\\/Thorsten_Vogl_4.9.20.jpg\",\"articleSection\":[\"Exp\u00e9dition de fret et logistique\",\"Schweiz\",\"Suisse\",\"Switzerland\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2021\\\/03\\\/15\\\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2021\\\/03\\\/15\\\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\\\/\",\"url\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2021\\\/03\\\/15\\\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\\\/\",\"name\":\"Arbitrage par vid\u00e9oconf\u00e9rence contre la volont\u00e9 d'une partie - Swisstrans.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2021\\\/03\\\/15\\\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2021\\\/03\\\/15\\\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/swisstrans.dashboard.brand-architecture.at\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/12\\\/Thorsten_Vogl_4.9.20.jpg\",\"datePublished\":\"2021-03-15T18:16:04+00:00\",\"dateModified\":\"2025-12-15T11:55:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2021\\\/03\\\/15\\\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2021\\\/03\\\/15\\\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2021\\\/03\\\/15\\\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/swisstrans.dashboard.brand-architecture.at\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/12\\\/Thorsten_Vogl_4.9.20.jpg\",\"contentUrl\":\"https:\\\/\\\/swisstrans.dashboard.brand-architecture.at\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/12\\\/Thorsten_Vogl_4.9.20.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2021\\\/03\\\/15\\\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arbitrage par vid\u00e9oconf\u00e9rence contre la volont\u00e9 d&rsquo;une partie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/\",\"name\":\"Swisstrans\",\"description\":\"Swisstrans est une plateforme d\u2019information sur le transport et la logistique en Suisse, active depuis 2002, qui met en relation les exp\u00e9diteurs et les fournisseurs de produits et services.\",\"publisher\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"alternateName\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swisstrans.info\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/01\\\/swisstrans_logo.png\",\"contentUrl\":\"https:\\\/\\\/swisstrans.info\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/01\\\/swisstrans_logo.png\",\"width\":823,\"height\":164,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/swisstrans-info\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arbitrage par vid\u00e9oconf\u00e9rence contre la volont\u00e9 d'une partie - Swisstrans.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swisstrans.info\/fr\/2021\/03\/15\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\/","og_locale":"fr_FR","og_type":"article","og_title":"Arbitrage par vid\u00e9oconf\u00e9rence contre la volont\u00e9 d'une partie - Swisstrans.","og_description":"Juste en p\u00e9riode de Corona, la question se pose \u00e9galement en cas de litiges dans le domaine de la logistique et du transport : comment obtenir [\u2026]","og_url":"https:\/\/swisstrans.info\/fr\/2021\/03\/15\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\/","og_site_name":"Swisstrans","article_published_time":"2021-03-15T18:16:04+00:00","article_modified_time":"2025-12-15T11:55:24+00:00","og_image":[{"url":"https:\/\/swisstrans.dashboard.brand-architecture.at\/wp-content\/uploads\/sites\/8\/2025\/12\/Thorsten_Vogl_4.9.20.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/swisstrans.info\/fr\/2021\/03\/15\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\/#article","isPartOf":{"@id":"https:\/\/swisstrans.info\/fr\/2021\/03\/15\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\/"},"author":{"name":"","@id":""},"headline":"Arbitrage par vid\u00e9oconf\u00e9rence contre la volont\u00e9 d&rsquo;une partie","datePublished":"2021-03-15T18:16:04+00:00","dateModified":"2025-12-15T11:55:24+00:00","mainEntityOfPage":{"@id":"https:\/\/swisstrans.info\/fr\/2021\/03\/15\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\/"},"wordCount":1587,"commentCount":0,"publisher":{"@id":"https:\/\/swisstrans.info\/fr\/#organization"},"image":{"@id":"https:\/\/swisstrans.info\/fr\/2021\/03\/15\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\/#primaryimage"},"thumbnailUrl":"https:\/\/swisstrans.dashboard.brand-architecture.at\/wp-content\/uploads\/sites\/8\/2025\/12\/Thorsten_Vogl_4.9.20.jpg","articleSection":["Exp\u00e9dition de fret et logistique","Schweiz","Suisse","Switzerland"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/swisstrans.info\/fr\/2021\/03\/15\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/swisstrans.info\/fr\/2021\/03\/15\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\/","url":"https:\/\/swisstrans.info\/fr\/2021\/03\/15\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\/","name":"Arbitrage par vid\u00e9oconf\u00e9rence contre la volont\u00e9 d'une partie - Swisstrans.","isPartOf":{"@id":"https:\/\/swisstrans.info\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/swisstrans.info\/fr\/2021\/03\/15\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\/#primaryimage"},"image":{"@id":"https:\/\/swisstrans.info\/fr\/2021\/03\/15\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\/#primaryimage"},"thumbnailUrl":"https:\/\/swisstrans.dashboard.brand-architecture.at\/wp-content\/uploads\/sites\/8\/2025\/12\/Thorsten_Vogl_4.9.20.jpg","datePublished":"2021-03-15T18:16:04+00:00","dateModified":"2025-12-15T11:55:24+00:00","breadcrumb":{"@id":"https:\/\/swisstrans.info\/fr\/2021\/03\/15\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swisstrans.info\/fr\/2021\/03\/15\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/swisstrans.info\/fr\/2021\/03\/15\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\/#primaryimage","url":"https:\/\/swisstrans.dashboard.brand-architecture.at\/wp-content\/uploads\/sites\/8\/2025\/12\/Thorsten_Vogl_4.9.20.jpg","contentUrl":"https:\/\/swisstrans.dashboard.brand-architecture.at\/wp-content\/uploads\/sites\/8\/2025\/12\/Thorsten_Vogl_4.9.20.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/swisstrans.info\/fr\/2021\/03\/15\/arbitrage-par-videoconference-contre-la-volonte-dune-partie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/swisstrans.info\/fr\/"},{"@type":"ListItem","position":2,"name":"Arbitrage par vid\u00e9oconf\u00e9rence contre la volont\u00e9 d&rsquo;une partie"}]},{"@type":"WebSite","@id":"https:\/\/swisstrans.info\/fr\/#website","url":"https:\/\/swisstrans.info\/fr\/","name":"Swisstrans","description":"Swisstrans est une plateforme d\u2019information sur le transport et la logistique en Suisse, active depuis 2002, qui met en relation les exp\u00e9diteurs et les fournisseurs de produits et services.","publisher":{"@id":"https:\/\/swisstrans.info\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swisstrans.info\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/swisstrans.info\/fr\/#organization","name":"Groupe Logismedia AG","alternateName":"Logismedia Group AG","url":"https:\/\/swisstrans.info\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/swisstrans.info\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2026\/01\/swisstrans_logo.png","contentUrl":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2026\/01\/swisstrans_logo.png","width":823,"height":164,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/swisstrans.info\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/showcase\/swisstrans-info\/"]}]}},"_links":{"self":[{"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/posts\/23957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/comments?post=23957"}],"version-history":[{"count":1,"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/posts\/23957\/revisions"}],"predecessor-version":[{"id":43638,"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/posts\/23957\/revisions\/43638"}],"wp:attachment":[{"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/media?parent=23957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/categories?post=23957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/tags?post=23957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}