{"id":56227,"date":"2022-05-09T21:25:58","date_gmt":"2022-05-09T19:25:58","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/05\/09\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\/"},"modified":"2022-05-09T21:25:58","modified_gmt":"2022-05-09T19:25:58","slug":"dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique","status":"publish","type":"post","link":"https:\/\/swisstrans.info\/fr\/2022\/05\/09\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\/","title":{"rendered":"DPD Suisse livre \u00e0 B\u00e2le le dernier kilom\u00e8tre de mani\u00e8re \u00e9cologique"},"content":{"rendered":"<h5><strong>Mardi, DPD Suisse a inaugur\u00e9 le premier Green CityHub dans le Smart City Lab de B\u00e2le, sur le site de Wolf. Cela permet \u00e0 la r\u00e9gion de B\u00e2le de b\u00e9n\u00e9ficier d&rsquo;un prestataire de services de colis qui utilise \u00e0 100 % des v\u00e9hicules \u00e9lectriques pour le dernier kilom\u00e8tre et r\u00e9duit les \u00e9missions. \u00c0 l&#8217;emplacement de B\u00e2le Wolf, DPD Suisse profite des synergies avec des partenaires du Smart City Lab de B\u00e2le.<\/strong><\/h5>\n<p>(Buchs\/B\u00e2le) L&rsquo;augmentation continue du volume des colis, en particulier dans les zones urbaines, pose un probl\u00e8me de plus en plus important pour l&rsquo;environnement et la population urbaine. La congestion des centres-villes due au trafic et aux \u00e9missions d&rsquo;une part, et la gestion de l&rsquo;augmentation du volume d&rsquo;autre part, repr\u00e9sentent un grand d\u00e9fi pour les entreprises de logistique. Le Green CityHub de B\u00e2le non seulement flexibilise la livraison du dernier kilom\u00e8tre, mais cr\u00e9e \u00e9galement une valeur ajout\u00e9e pour les personnes et l&rsquo;environnement.<\/p>\n<p>Gr\u00e2ce au nouveau Green CityHub dans le Smart City Lab de B\u00e2le, DPD Suisse livre une autre ville de mani\u00e8re enti\u00e8rement \u00e9cologique pour le dernier kilom\u00e8tre, en plus des villes de Schaffhouse et de Gen\u00e8ve. Ainsi, DPD Suisse se rapproche de son objectif d&rsquo;offrir un transport enti\u00e8rement \u00e9cologique dans 10 villes suisses d&rsquo;ici 2025.<\/p>\n<h5>Green CityHub B\u00e2le officiellement en service<\/h5>\n<p>Lors de la c\u00e9r\u00e9monie d&rsquo;inauguration du 3 mai 2022, le Green CityHub a \u00e9t\u00e9 officiellement mis en service. Les partenaires du Smart City Lab de B\u00e2le ainsi que d&rsquo;autres partenaires ont \u00e9t\u00e9 invit\u00e9s. Apr\u00e8s un bref discours d&rsquo;inauguration, le ruban a \u00e9t\u00e9 coup\u00e9 symboliquement. Un repr\u00e9sentant de l&rsquo;entreprise partenaire de DPD, Manor AG, d\u00e9clare : \u00ab Une livraison de colis neutre en CO2 devrait \u00eatre encourag\u00e9e dans chaque ville&#8230; Continuez ainsi ! \u00bb. Un employ\u00e9 de l&rsquo;administration de la ville de B\u00e2le ajoute : \u00ab L&#8217;emplacement \u00e0 Wolf est id\u00e9al pour une livraison \u00e9cologique dans la ville de B\u00e2le. Ce site est central et important pour l&rsquo;avenir. \u00bb.<\/p>\n<p>Le Smart City Lab de B\u00e2le favorise les innovations dans les domaines des b\u00e2timents, de la mobilit\u00e9, de la logistique urbaine et au-del\u00e0, pour une Suisse de demain vivable, durable et comp\u00e9titive. Il offre un espace et des formats pour connecter les acteurs, d\u00e9velopper des solutions, tester des id\u00e9es et d\u00e9couvrir des solutions intelligentes.<\/p>\n<h5>Collaboration avec diff\u00e9rents partenaires<\/h5>\n<p>DPD Suisse collabore sur place avec diff\u00e9rents partenaires du Smart City Lab de B\u00e2le. En plus de ses propres e-vans pour la livraison directement \u00e0 la porte, les colis sont \u00e9galement livr\u00e9s dans des Parcel Lockers dans le centre-ville de B\u00e2le, g\u00e9r\u00e9s par l&rsquo;op\u00e9rateur de distributeurs automatiques de colis \u00ab SchlaueBox \u00bb. Cela permet aux destinataires de r\u00e9cup\u00e9rer leur colis quand cela leur convient. Gr\u00e2ce \u00e0 la collaboration avec l&rsquo;entreprise UpVolt, les e-vans sont charg\u00e9s avec de l&rsquo;\u00e9lectricit\u00e9 \u00e9cologique.<\/p>\n<p>La livraison \u00e9lectrifi\u00e9e r\u00e9duit les \u00e9missions de CO2 de 70 %. Gr\u00e2ce au Green CityHub, environ 11 000 km de trajets sont \u00e9conomis\u00e9s chaque mois. Les colis sont pr\u00e9-tri\u00e9s la nuit dans le d\u00e9p\u00f4t de M\u00f6hlin et transport\u00e9s par camion au Green CityHub Wolf. L\u00e0, les e-vans sont charg\u00e9s et les envois sont livr\u00e9s.<\/p>\n<h5>Faits &amp; Chiffres Green CityHub B\u00e2le Wolf :<\/h5>\n<ul>\n<li>Nombre de colis pr\u00e9vu par mois pour la livraison : 26 000<\/li>\n<li>Taille du Green CityHub : 300 m2 de surface int\u00e9rieure plus 290 m2 de surface ext\u00e9rieure<\/li>\n<li>10 e-vans<\/li>\n<li>8 tourn\u00e9es et 2 tourn\u00e9es de renfort<\/li>\n<\/ul>\n<p>Pour DPD Suisse, la responsabilit\u00e9 envers l&rsquo;environnement est une obligation. Le prestataire de services de colis livre chaque colis de mani\u00e8re neutre en CO2 depuis 2012 \u2013 sans co\u00fbts suppl\u00e9mentaires pour les clientes et clients. Cela se fait en mesurant ses \u00e9missions de CO2, en les r\u00e9duisant continuellement et en compensant toutes les \u00e9missions de CO2 restantes.<\/p>\n<p>Photo : \u00a9 DPD<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mardi, DPD Suisse a inaugur\u00e9 le premier Green CityHub dans le Smart City Lab de B\u00e2le, sur le site de Wolf. Cela permet \u00e0 la r\u00e9gion<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10321,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6732,6364,6370,6367],"tags":[],"class_list":["post-56227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intermodal-route","category-schweiz","category-suisse","category-switzerland"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DPD Suisse livre \u00e0 B\u00e2le le dernier kilom\u00e8tre de mani\u00e8re \u00e9cologique - Swisstrans.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swisstrans.info\/fr\/2022\/05\/09\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DPD Suisse livre \u00e0 B\u00e2le le dernier kilom\u00e8tre de mani\u00e8re \u00e9cologique - Swisstrans.\" \/>\n<meta property=\"og:description\" content=\"Mardi, DPD Suisse a inaugur\u00e9 le premier Green CityHub dans le Smart City Lab de B\u00e2le, sur le site de Wolf. Cela permet \u00e0 la r\u00e9gion [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swisstrans.info\/fr\/2022\/05\/09\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\/\" \/>\n<meta property=\"og:site_name\" content=\"Swisstrans\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-09T19:25:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2025\/12\/DPD_9.5.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1164\" \/>\n\t<meta property=\"og:image:height\" content=\"592\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2022\\\/05\\\/09\\\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2022\\\/05\\\/09\\\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"DPD Suisse livre \u00e0 B\u00e2le le dernier kilom\u00e8tre de mani\u00e8re \u00e9cologique\",\"datePublished\":\"2022-05-09T19:25:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2022\\\/05\\\/09\\\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\\\/\"},\"wordCount\":690,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2022\\\/05\\\/09\\\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/swisstrans.info\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/12\\\/DPD_9.5.22.jpg\",\"articleSection\":[\"Intermodal \\\/ Route\",\"Schweiz\",\"Suisse\",\"Switzerland\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2022\\\/05\\\/09\\\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2022\\\/05\\\/09\\\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\\\/\",\"url\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2022\\\/05\\\/09\\\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\\\/\",\"name\":\"DPD Suisse livre \u00e0 B\u00e2le le dernier kilom\u00e8tre de mani\u00e8re \u00e9cologique - Swisstrans.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2022\\\/05\\\/09\\\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2022\\\/05\\\/09\\\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/swisstrans.info\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/12\\\/DPD_9.5.22.jpg\",\"datePublished\":\"2022-05-09T19:25:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2022\\\/05\\\/09\\\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2022\\\/05\\\/09\\\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2022\\\/05\\\/09\\\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/swisstrans.info\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/12\\\/DPD_9.5.22.jpg\",\"contentUrl\":\"https:\\\/\\\/swisstrans.info\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/12\\\/DPD_9.5.22.jpg\",\"width\":1164,\"height\":592},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2022\\\/05\\\/09\\\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DPD Suisse livre \u00e0 B\u00e2le le dernier kilom\u00e8tre de mani\u00e8re \u00e9cologique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/\",\"name\":\"Swisstrans\",\"description\":\"Swisstrans est une plateforme d\u2019information sur le transport et la logistique en Suisse, active depuis 2002, qui met en relation les exp\u00e9diteurs et les fournisseurs de produits et services.\",\"publisher\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"alternateName\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swisstrans.info\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/01\\\/swisstrans_logo.png\",\"contentUrl\":\"https:\\\/\\\/swisstrans.info\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/01\\\/swisstrans_logo.png\",\"width\":823,\"height\":164,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/swisstrans-info\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DPD Suisse livre \u00e0 B\u00e2le le dernier kilom\u00e8tre de mani\u00e8re \u00e9cologique - Swisstrans.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swisstrans.info\/fr\/2022\/05\/09\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\/","og_locale":"fr_FR","og_type":"article","og_title":"DPD Suisse livre \u00e0 B\u00e2le le dernier kilom\u00e8tre de mani\u00e8re \u00e9cologique - Swisstrans.","og_description":"Mardi, DPD Suisse a inaugur\u00e9 le premier Green CityHub dans le Smart City Lab de B\u00e2le, sur le site de Wolf. Cela permet \u00e0 la r\u00e9gion [\u2026]","og_url":"https:\/\/swisstrans.info\/fr\/2022\/05\/09\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\/","og_site_name":"Swisstrans","article_published_time":"2022-05-09T19:25:58+00:00","og_image":[{"width":1164,"height":592,"url":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2025\/12\/DPD_9.5.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/swisstrans.info\/fr\/2022\/05\/09\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\/#article","isPartOf":{"@id":"https:\/\/swisstrans.info\/fr\/2022\/05\/09\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\/"},"author":{"name":"","@id":""},"headline":"DPD Suisse livre \u00e0 B\u00e2le le dernier kilom\u00e8tre de mani\u00e8re \u00e9cologique","datePublished":"2022-05-09T19:25:58+00:00","mainEntityOfPage":{"@id":"https:\/\/swisstrans.info\/fr\/2022\/05\/09\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\/"},"wordCount":690,"commentCount":0,"publisher":{"@id":"https:\/\/swisstrans.info\/fr\/#organization"},"image":{"@id":"https:\/\/swisstrans.info\/fr\/2022\/05\/09\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\/#primaryimage"},"thumbnailUrl":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2025\/12\/DPD_9.5.22.jpg","articleSection":["Intermodal \/ Route","Schweiz","Suisse","Switzerland"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/swisstrans.info\/fr\/2022\/05\/09\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/swisstrans.info\/fr\/2022\/05\/09\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\/","url":"https:\/\/swisstrans.info\/fr\/2022\/05\/09\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\/","name":"DPD Suisse livre \u00e0 B\u00e2le le dernier kilom\u00e8tre de mani\u00e8re \u00e9cologique - Swisstrans.","isPartOf":{"@id":"https:\/\/swisstrans.info\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/swisstrans.info\/fr\/2022\/05\/09\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\/#primaryimage"},"image":{"@id":"https:\/\/swisstrans.info\/fr\/2022\/05\/09\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\/#primaryimage"},"thumbnailUrl":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2025\/12\/DPD_9.5.22.jpg","datePublished":"2022-05-09T19:25:58+00:00","breadcrumb":{"@id":"https:\/\/swisstrans.info\/fr\/2022\/05\/09\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swisstrans.info\/fr\/2022\/05\/09\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/swisstrans.info\/fr\/2022\/05\/09\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\/#primaryimage","url":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2025\/12\/DPD_9.5.22.jpg","contentUrl":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2025\/12\/DPD_9.5.22.jpg","width":1164,"height":592},{"@type":"BreadcrumbList","@id":"https:\/\/swisstrans.info\/fr\/2022\/05\/09\/dpd-suisse-livre-a-bale-le-dernier-kilometre-de-maniere-ecologique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/swisstrans.info\/fr\/"},{"@type":"ListItem","position":2,"name":"DPD Suisse livre \u00e0 B\u00e2le le dernier kilom\u00e8tre de mani\u00e8re \u00e9cologique"}]},{"@type":"WebSite","@id":"https:\/\/swisstrans.info\/fr\/#website","url":"https:\/\/swisstrans.info\/fr\/","name":"Swisstrans","description":"Swisstrans est une plateforme d\u2019information sur le transport et la logistique en Suisse, active depuis 2002, qui met en relation les exp\u00e9diteurs et les fournisseurs de produits et services.","publisher":{"@id":"https:\/\/swisstrans.info\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swisstrans.info\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/swisstrans.info\/fr\/#organization","name":"Groupe Logismedia AG","alternateName":"Logismedia Group AG","url":"https:\/\/swisstrans.info\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/swisstrans.info\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2026\/01\/swisstrans_logo.png","contentUrl":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2026\/01\/swisstrans_logo.png","width":823,"height":164,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/swisstrans.info\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/showcase\/swisstrans-info\/"]}]}},"_links":{"self":[{"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/posts\/56227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/comments?post=56227"}],"version-history":[{"count":0,"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/posts\/56227\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/media\/10321"}],"wp:attachment":[{"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/media?parent=56227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/categories?post=56227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/tags?post=56227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}