{"id":61996,"date":"2023-07-18T16:11:10","date_gmt":"2023-07-18T14:11:10","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/07\/18\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\/"},"modified":"2023-07-18T16:11:10","modified_gmt":"2023-07-18T14:11:10","slug":"le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse","status":"publish","type":"post","link":"https:\/\/swisstrans.info\/fr\/2023\/07\/18\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\/","title":{"rendered":"Le groupe Bertschi inaugure une succursale dans le delta du Yangts\u00e9"},"content":{"rendered":"<h5>Le groupe Bertschi, un prestataire de services logistiques multinational suisse, est heureux d&rsquo;annoncer le succ\u00e8s de l&rsquo;inauguration de son Zhangjiagang Liquids Chemical Hub. L&rsquo;\u00e9v\u00e9nement a eu lieu les 5 et 6 juillet et a \u00e9t\u00e9 marqu\u00e9 par la pr\u00e9sence de hauts repr\u00e9sentants gouvernementaux et de plus de 250 clients estim\u00e9s. Le nouveau hub, situ\u00e9 au c\u0153ur du delta du fleuve Yangts\u00e9, est consid\u00e9r\u00e9 comme l&rsquo;un des centres de logistique chimique les plus s\u00fbrs et durables en Chine et marque une \u00e9tape importante dans l&rsquo;histoire de l&rsquo;entreprise Bertschi.<\/h5>\n<p>(D\u00fcrren\u00e4sch\/Zhangjiagang) Apr\u00e8s une dur\u00e9e totale de projet de 6 ans et la gestion de nombreux d\u00e9fis, y compris l&rsquo;\u00e9pid\u00e9mie inattendue de la pand\u00e9mie de COVID-19, les c\u00e9l\u00e9brations de l&rsquo;inauguration officielle \u00e9taient bien m\u00e9rit\u00e9es pour toutes les personnes impliqu\u00e9es. \u00c9tant donn\u00e9 que le hub est op\u00e9rationnel depuis le d\u00e9but de l&rsquo;ann\u00e9e, l&rsquo;\u00e9v\u00e9nement a \u00e9t\u00e9 une excellente occasion de d\u00e9montrer aux clients l&rsquo;impressionnante infrastructure et l&rsquo;offre de services de ce centre logistique unique.<\/p>\n<h5><strong>Portefeuille de services \u00e0 valeur ajout\u00e9e pour les marchandises dangereuses chimiques<\/strong><\/h5>\n<p>Le hub est une installation moderne et s\u00e9curis\u00e9e pour les marchandises dangereuses, avec une capacit\u00e9 de stockage de 50 000 tonnes et une capacit\u00e9 de traitement annuelle de plus de 500 000 tonnes de divers produits chimiques. Il se distingue par un entrep\u00f4t de citernes isotank d&rsquo;une capacit\u00e9 allant jusqu&rsquo;\u00e0 1 100 conteneurs-citernes de marchandises dangereuses charg\u00e9s, ainsi que trois entrep\u00f4ts avec une capacit\u00e9 totale de 25 000 palettes de diff\u00e9rentes classes de marchandises dangereuses. Une installation automatis\u00e9e de remplissage de f\u00fbts garantit une productivit\u00e9 maximale lors du remplissage de f\u00fbts et d&rsquo;IBC. Avec des options de chauffage et de refroidissement avanc\u00e9es pour les conteneurs, y compris la vapeur, l&rsquo;eau chaude, le chauffage \u00e9lectrique et le refroidissement \u00e9lectrique, le hub offre aux clients de l&rsquo;industrie chimique une large gamme de services \u00e0 valeur ajout\u00e9e.<\/p>\n<h5><strong>Emplacement strat\u00e9giquement id\u00e9al dans le delta du fleuve Yangts\u00e9<\/strong><\/h5>\n<p>Le hub est situ\u00e9 dans le florissant parc industriel chimique international du fleuve Yangts\u00e9, \u00e0 c\u00f4t\u00e9 de la zone de libre-\u00e9change de Zhangjiagang, et b\u00e9n\u00e9ficie de son emplacement strat\u00e9gique dans l&rsquo;une des r\u00e9gions \u00e9conomiques les plus dynamiques de Chine. La position au bord du fleuve Yangts\u00e9 garantit \u00e9galement une connexion fluide aux r\u00e9seaux de transport mondiaux et une distribution efficace des produits chimiques \u00e0 travers la Chine et au-del\u00e0. \u00ab\u00a0Le hub compl\u00e8te id\u00e9alement le r\u00e9seau logistique mondial de Bertschi et permet des solutions de cha\u00eenes d&rsquo;approvisionnement porte-\u00e0-porte \u00e0 l&rsquo;\u00e9chelle mondiale, soutenant nos clients dans leurs plans d&rsquo;expansion rapide en Chine et dans toute l&rsquo;Asie\u00a0\u00bb, explique Jan Arnet, PDG du groupe Bertschi.<\/p>\n<p>L&rsquo;entrep\u00f4t de conteneurs est \u00e9galement ouvert aux conteneurs-citernes de tous les op\u00e9rateurs ; cela permet aux exp\u00e9diteurs de produits chimiques d&rsquo;utiliser la ferme de conteneurs comme un hub d&rsquo;entr\u00e9e durable dans le delta du Yangts\u00e9 pour le stockage de produits dans les syst\u00e8mes informatiques interop\u00e9rables des prestataires de services isotank.<\/p>\n<p>Le nouveau centre de logistique chimique est situ\u00e9 \u00e0 proximit\u00e9 imm\u00e9diate du port de Zhangjiagang, d&rsquo;o\u00f9 partent quotidiennement des navires feeders de conteneurs vers le plus grand port du monde, Shanghai, situ\u00e9 \u00e0 150 kilom\u00e8tres, ainsi que des liaisons maritimes directes vers la Cor\u00e9e et le Japon. Cet emplacement permet au hub de soutenir l&rsquo;objectif politique de transf\u00e9rer le transit routier des marchandises dangereuses entre le port de Shanghai et l&rsquo;arri\u00e8re-pays vers des barges fluviales, all\u00e9geant ainsi les routes de la r\u00e9gion m\u00e9tropolitaine de Shanghai, qui compte 25 millions d&rsquo;habitants. Gr\u00e2ce \u00e0 ce transfert de trafic de la route vers la voie navigable, la s\u00e9curit\u00e9 routi\u00e8re et la durabilit\u00e9 peuvent \u00eatre am\u00e9lior\u00e9es et les impacts environnementaux n\u00e9gatifs minimis\u00e9s.<br \/>\n<strong>Grande c\u00e9r\u00e9monie d&rsquo;inauguration<\/strong><\/p>\n<p>La c\u00e9r\u00e9monie d&rsquo;inauguration du Zhangjiagang Liquids Hub repr\u00e9sente une \u00e9tape remarquable dans l&rsquo;histoire de l&rsquo;entreprise Bertschi. \u00ab\u00a0L&rsquo;installation est le plus grand investissement unique de notre histoire. Elle signale notre engagement fort envers la croissance et le succ\u00e8s de nos clients du monde entier en Chine\u00a0\u00bb, d\u00e9clare Hans-J\u00f6rg Bertschi, pr\u00e9sident ex\u00e9cutif du groupe Bertschi. L&rsquo;\u00e9v\u00e9nement de deux jours a mis en lumi\u00e8re l&rsquo;engagement de Bertschi \u00e0 offrir \u00e0 ses clients une exp\u00e9rience in\u00e9gal\u00e9e. En pr\u00e9sence du consul g\u00e9n\u00e9ral de Suisse \u00e0 Shanghai, Sacha Bachmann, du secr\u00e9taire du comit\u00e9 municipal du parti de Zhangjiagang, M. Han, d&rsquo;un membre permanent du comit\u00e9 municipal du parti de Zhangjiagang, M. Lu, de la vice-maire de l&rsquo;administration municipale de Zhangjiagang, Mme Weng, de clients estim\u00e9s et des \u00e9quipes de direction du groupe Bertschi et de Bertschi China, l&rsquo;occasion a pu souligner la port\u00e9e mondiale et l&rsquo;engagement de Bertschi \u00e0 servir le march\u00e9 chinois.<\/p>\n<h5>Un signe de services durables et efficaces pour l&rsquo;industrie chimique<\/h5>\n<p>Avec la mise en service du Zhangjiagang Liquids Hub, Bertschi poursuit son inlassable qu\u00eate de services de cha\u00eene d&rsquo;approvisionnement robustes, durables et efficaces pour l&rsquo;industrie chimique. L&rsquo;infrastructure avanc\u00e9e, l&#8217;emplacement strat\u00e9gique, l&rsquo;engagement envers la s\u00e9curit\u00e9 et la durabilit\u00e9, ainsi que la technologie innovante du hub en font un pionnier dans la logistique chimique, r\u00e9pondant aux besoins changeants des clients.<\/p>\n<p>Photo : \u00a9 Bertschi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le groupe Bertschi, un prestataire de services logistiques multinational suisse, est heureux d&rsquo;annoncer le succ\u00e8s de l&rsquo;inauguration de son Zhangjiagang Liquids Chemical Hub. L&rsquo;\u00e9v\u00e9nement a eu<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":7875,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6364,6370,6367],"tags":[],"class_list":["post-61996","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schweiz","category-suisse","category-switzerland"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le groupe Bertschi inaugure une succursale dans le delta du Yangts\u00e9 - Swisstrans.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swisstrans.info\/fr\/2023\/07\/18\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le groupe Bertschi inaugure une succursale dans le delta du Yangts\u00e9 - Swisstrans.\" \/>\n<meta property=\"og:description\" content=\"Le groupe Bertschi, un prestataire de services logistiques multinational suisse, est heureux d&rsquo;annoncer le succ\u00e8s de l&rsquo;inauguration de son Zhangjiagang Liquids Chemical Hub. L&rsquo;\u00e9v\u00e9nement a eu [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swisstrans.info\/fr\/2023\/07\/18\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\/\" \/>\n<meta property=\"og:site_name\" content=\"Swisstrans\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-18T14:11:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2025\/12\/Bertschi_18.7.23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1196\" \/>\n\t<meta property=\"og:image:height\" content=\"669\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2023\\\/07\\\/18\\\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2023\\\/07\\\/18\\\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Le groupe Bertschi inaugure une succursale dans le delta du Yangts\u00e9\",\"datePublished\":\"2023-07-18T14:11:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2023\\\/07\\\/18\\\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\\\/\"},\"wordCount\":940,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2023\\\/07\\\/18\\\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/swisstrans.info\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/12\\\/Bertschi_18.7.23.jpg\",\"articleSection\":[\"Schweiz\",\"Suisse\",\"Switzerland\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2023\\\/07\\\/18\\\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2023\\\/07\\\/18\\\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\\\/\",\"url\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2023\\\/07\\\/18\\\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\\\/\",\"name\":\"Le groupe Bertschi inaugure une succursale dans le delta du Yangts\u00e9 - Swisstrans.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2023\\\/07\\\/18\\\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2023\\\/07\\\/18\\\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/swisstrans.info\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/12\\\/Bertschi_18.7.23.jpg\",\"datePublished\":\"2023-07-18T14:11:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2023\\\/07\\\/18\\\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2023\\\/07\\\/18\\\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2023\\\/07\\\/18\\\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/swisstrans.info\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/12\\\/Bertschi_18.7.23.jpg\",\"contentUrl\":\"https:\\\/\\\/swisstrans.info\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/12\\\/Bertschi_18.7.23.jpg\",\"width\":1196,\"height\":669},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/2023\\\/07\\\/18\\\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le groupe Bertschi inaugure une succursale dans le delta du Yangts\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/\",\"name\":\"Swisstrans\",\"description\":\"Swisstrans est une plateforme d\u2019information sur le transport et la logistique en Suisse, active depuis 2002, qui met en relation les exp\u00e9diteurs et les fournisseurs de produits et services.\",\"publisher\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"alternateName\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swisstrans.info\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/01\\\/swisstrans_logo.png\",\"contentUrl\":\"https:\\\/\\\/swisstrans.info\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/01\\\/swisstrans_logo.png\",\"width\":823,\"height\":164,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/swisstrans-info\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le groupe Bertschi inaugure une succursale dans le delta du Yangts\u00e9 - Swisstrans.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swisstrans.info\/fr\/2023\/07\/18\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\/","og_locale":"fr_FR","og_type":"article","og_title":"Le groupe Bertschi inaugure une succursale dans le delta du Yangts\u00e9 - Swisstrans.","og_description":"Le groupe Bertschi, un prestataire de services logistiques multinational suisse, est heureux d&rsquo;annoncer le succ\u00e8s de l&rsquo;inauguration de son Zhangjiagang Liquids Chemical Hub. L&rsquo;\u00e9v\u00e9nement a eu [\u2026]","og_url":"https:\/\/swisstrans.info\/fr\/2023\/07\/18\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\/","og_site_name":"Swisstrans","article_published_time":"2023-07-18T14:11:10+00:00","og_image":[{"width":1196,"height":669,"url":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2025\/12\/Bertschi_18.7.23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/swisstrans.info\/fr\/2023\/07\/18\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\/#article","isPartOf":{"@id":"https:\/\/swisstrans.info\/fr\/2023\/07\/18\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\/"},"author":{"name":"","@id":""},"headline":"Le groupe Bertschi inaugure une succursale dans le delta du Yangts\u00e9","datePublished":"2023-07-18T14:11:10+00:00","mainEntityOfPage":{"@id":"https:\/\/swisstrans.info\/fr\/2023\/07\/18\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\/"},"wordCount":940,"commentCount":0,"publisher":{"@id":"https:\/\/swisstrans.info\/fr\/#organization"},"image":{"@id":"https:\/\/swisstrans.info\/fr\/2023\/07\/18\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\/#primaryimage"},"thumbnailUrl":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2025\/12\/Bertschi_18.7.23.jpg","articleSection":["Schweiz","Suisse","Switzerland"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/swisstrans.info\/fr\/2023\/07\/18\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/swisstrans.info\/fr\/2023\/07\/18\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\/","url":"https:\/\/swisstrans.info\/fr\/2023\/07\/18\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\/","name":"Le groupe Bertschi inaugure une succursale dans le delta du Yangts\u00e9 - Swisstrans.","isPartOf":{"@id":"https:\/\/swisstrans.info\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/swisstrans.info\/fr\/2023\/07\/18\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\/#primaryimage"},"image":{"@id":"https:\/\/swisstrans.info\/fr\/2023\/07\/18\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\/#primaryimage"},"thumbnailUrl":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2025\/12\/Bertschi_18.7.23.jpg","datePublished":"2023-07-18T14:11:10+00:00","breadcrumb":{"@id":"https:\/\/swisstrans.info\/fr\/2023\/07\/18\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swisstrans.info\/fr\/2023\/07\/18\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/swisstrans.info\/fr\/2023\/07\/18\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\/#primaryimage","url":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2025\/12\/Bertschi_18.7.23.jpg","contentUrl":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2025\/12\/Bertschi_18.7.23.jpg","width":1196,"height":669},{"@type":"BreadcrumbList","@id":"https:\/\/swisstrans.info\/fr\/2023\/07\/18\/le-groupe-bertschi-inaugure-une-succursale-dans-le-delta-du-yangtse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/swisstrans.info\/fr\/"},{"@type":"ListItem","position":2,"name":"Le groupe Bertschi inaugure une succursale dans le delta du Yangts\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/swisstrans.info\/fr\/#website","url":"https:\/\/swisstrans.info\/fr\/","name":"Swisstrans","description":"Swisstrans est une plateforme d\u2019information sur le transport et la logistique en Suisse, active depuis 2002, qui met en relation les exp\u00e9diteurs et les fournisseurs de produits et services.","publisher":{"@id":"https:\/\/swisstrans.info\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swisstrans.info\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/swisstrans.info\/fr\/#organization","name":"Groupe Logismedia AG","alternateName":"Logismedia Group AG","url":"https:\/\/swisstrans.info\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/swisstrans.info\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2026\/01\/swisstrans_logo.png","contentUrl":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2026\/01\/swisstrans_logo.png","width":823,"height":164,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/swisstrans.info\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/showcase\/swisstrans-info\/"]}]}},"_links":{"self":[{"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/posts\/61996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/comments?post=61996"}],"version-history":[{"count":0,"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/posts\/61996\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/media\/7875"}],"wp:attachment":[{"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/media?parent=61996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/categories?post=61996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/swisstrans.info\/fr\/wp-json\/wp\/v2\/tags?post=61996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}