{"id":65132,"date":"2024-05-03T16:33:33","date_gmt":"2024-05-03T14:33:33","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/05\/03\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\/"},"modified":"2024-05-03T16:33:33","modified_gmt":"2024-05-03T14:33:33","slug":"il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento","status":"publish","type":"post","link":"https:\/\/swisstrans.info\/it\/2024\/05\/03\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\/","title":{"rendered":"Il forum della logistica del VNL affronta i mondi del lavoro in cambiamento"},"content":{"rendered":"<h5><strong>Il forum della logistica del VNL Svizzera del 6 giugno 2024 a Lucerna riunisce esperti del mondo economico e scientifico, dell&#8217;istruzione, della ricerca e della tecnologia, per scambiare idee, portare le proprie prospettive in modo interdisciplinare e trovare insieme approcci sostenibili alle soluzioni.<\/strong><\/h5>\n<p>(Zurigo\/Lucerna) Per orientarsi con successo in un ambiente dinamico e complesso, come quello che viviamo oggi, e prendere le decisioni giuste, \u00e8 pi\u00f9 importante che mai lo scambio tra professionisti e dirigenti nei settori degli acquisti, della logistica e della gestione della catena di approvvigionamento (SCM) sulle ultime evoluzioni, sulle best practice e sugli approcci promettenti alle soluzioni.<\/p>\n<h5><strong>Motivo: Mondi del lavoro in cambiamento \u2013 Come le tecnologie e la sostenibilit\u00e0 stanno trasformando la logistica e la SCM<\/strong><\/h5>\n<p>Cosa hanno a che fare l&#8217;intelligenza artificiale e i diritti umani con questo? Il professor Peter Kirschschl\u00e4ger, esperto riconosciuto in questo campo, tra l&#8217;altro Ordinario di Etica Teologica e direttore dell&#8217;Istituto di Etica Sociale ISE all&#8217;Universit\u00e0 di Lucerna e professore ospite alla cattedra di Neuroinformatica e Sistemi Neurali del ETH di Zurigo, ci dar\u00e0 nella sua keynote uno sguardo su questo campo di tensione.<\/p>\n<p>Un ruolo importante avr\u00e0 anche lo sviluppo futuro del trasporto merci autonomo. Martin Neubauer, amministratore delegato della Societ\u00e0 svizzera per la mobilit\u00e0 autonoma (SAAM), ci porter\u00e0 nel mondo della guida autonoma e del cambiamento imminente verso l&#8217;autonomia del trasporto merci.<\/p>\n<p>In sei sessioni di approfondimento saranno discussi gli effetti sulla SCM, sui sistemi di magazzino e trasporto, sulla logistica edile, sulla formazione e sull&#8217;acquisto. Insieme ai nostri co-organizzatori, il Logistikum Svizzera, l&#8217;Associazione per l&#8217;Intralogistica (ILS), l&#8217;Associazione svizzera per la formazione professionale nella logistica - ASFL\/SVBL e l&#8217;associazione professionale per gli acquisti e la gestione della catena di approvvigionamento procure.ch, \u00e8 emerso un panorama e prospettive variegate.<\/p>\n<p>Sponsor e partner del 7\u00b0 forum della logistica VNL:<\/p>\n<h5><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-26006 size-full\" src=\"https:\/\/swisstrans.dashboard.brand-architecture.at\/wp-content\/uploads\/sites\/8\/2025\/12\/VNL_3.5.24.jpg_4.jpg.png\" alt=\"\" width=\"1077\" height=\"168\" \/>Relatori di alto livello<\/h5>\n<p>I relatori ed esperti del mondo economico e della ricerca offrono approfondimenti esclusivi e condividono le loro esperienze. Il formato VNL offre uno scambio intenso tra i partecipanti del mondo economico e scientifico, tra cui:<\/p>\n<p>Beat D\u00fcrler, presidente SVBL - Mathias Siegenthaler, Logjob \u2013 CEO Daniel Gilgen, Gilgen CEO Christian Eiholzer, Head Supply Chain CKW - Mile Gavrilovic, Welti-Furrer - Dr. Sven-Erik Jacobsen, Amberg Loglay - Calvin Klein, T. Auer, Istituto per la gestione della catena di approvvigionamento, Universit\u00e0 di San Gallo - Philippe Zimmermann &amp; Thomas Heynen, Adnovum Brabender, Klenk, Brabender Group - Lara Amin, Loxo - Randy Drenth, Marius Schlegel, Swisscom - Tobias Koster, Thommen AG - Thomas Laarz, Dassault System<\/p>\n<h5><strong>Cambiamento dei mondi del lavoro nella logistica e nella catena di approvvigionamento<\/strong><\/h5>\n<p>Il forum della logistica Svizzera offre da anni una piattaforma di prima classe e unica per discutere insieme i cambiamenti rilevanti dei mondi del lavoro nella logistica e nella gestione della catena di approvvigionamento del futuro. I partecipanti rafforzano nel dialogo interattivo la loro capacit\u00e0 decisionale e di azione.<\/p>\n<h4><a href=\"https:\/\/www.logistikforumschweiz.com\/\" target=\"_blank\" rel=\"noopener\"><strong>Ulteriori informazioni e registrazione qui<\/strong><\/a><\/h4>\n<p>Foto: \u00a9 VNL Svizzera<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il forum della logistica del VNL Svizzera del 6 giugno 2024 a Lucerna riunisce esperti del mondo economico e scientifico, dell&#8217;istruzione, della ricerca e della tecnologia,<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":6580,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6364,6368,6367],"tags":[],"class_list":["post-65132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schweiz","category-svizzera","category-switzerland"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>-<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swisstrans.info\/it\/2024\/05\/03\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"-\" \/>\n<meta property=\"og:description\" content=\"Il forum della logistica del VNL Svizzera del 6 giugno 2024 a Lucerna riunisce esperti del mondo economico e scientifico, dell&#8217;istruzione, della ricerca e della tecnologia, [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swisstrans.info\/it\/2024\/05\/03\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\/\" \/>\n<meta property=\"og:site_name\" content=\"Swisstrans\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-03T14:33:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2025\/12\/VNL_3.5.24_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2414\" \/>\n\t<meta property=\"og:image:height\" content=\"1564\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/it\\\/2024\\\/05\\\/03\\\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/it\\\/2024\\\/05\\\/03\\\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Il forum della logistica del VNL affronta i mondi del lavoro in cambiamento\",\"datePublished\":\"2024-05-03T14:33:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/it\\\/2024\\\/05\\\/03\\\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\\\/\"},\"wordCount\":508,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/it\\\/2024\\\/05\\\/03\\\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/swisstrans.info\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/12\\\/VNL_3.5.24_2.jpg\",\"articleSection\":[\"Schweiz\",\"Svizzera\",\"Switzerland\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/swisstrans.info\\\/it\\\/2024\\\/05\\\/03\\\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/it\\\/2024\\\/05\\\/03\\\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\\\/\",\"url\":\"https:\\\/\\\/swisstrans.info\\\/it\\\/2024\\\/05\\\/03\\\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\\\/\",\"name\":\"-\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/it\\\/2024\\\/05\\\/03\\\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/it\\\/2024\\\/05\\\/03\\\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/swisstrans.info\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/12\\\/VNL_3.5.24_2.jpg\",\"datePublished\":\"2024-05-03T14:33:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/it\\\/2024\\\/05\\\/03\\\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swisstrans.info\\\/it\\\/2024\\\/05\\\/03\\\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/it\\\/2024\\\/05\\\/03\\\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/swisstrans.info\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/12\\\/VNL_3.5.24_2.jpg\",\"contentUrl\":\"https:\\\/\\\/swisstrans.info\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/12\\\/VNL_3.5.24_2.jpg\",\"width\":2414,\"height\":1564},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/it\\\/2024\\\/05\\\/03\\\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/swisstrans.info\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il forum della logistica del VNL affronta i mondi del lavoro in cambiamento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/swisstrans.info\\\/it\\\/\",\"name\":\"Swisstrans\",\"description\":\"Swisstrans \u00e8 una piattaforma informativa per il trasporto e la logistica in Svizzera, attiva dal 2002, che mette in contatto spedizionieri e fornitori di prodotti e servizi.\",\"publisher\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swisstrans.info\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"alternateName\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/swisstrans.info\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swisstrans.info\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/01\\\/swisstrans_logo.png\",\"contentUrl\":\"https:\\\/\\\/swisstrans.info\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/01\\\/swisstrans_logo.png\",\"width\":823,\"height\":164,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/swisstrans-info\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"-","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swisstrans.info\/it\/2024\/05\/03\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\/","og_locale":"it_IT","og_type":"article","og_title":"-","og_description":"Il forum della logistica del VNL Svizzera del 6 giugno 2024 a Lucerna riunisce esperti del mondo economico e scientifico, dell&#8217;istruzione, della ricerca e della tecnologia, [\u2026]","og_url":"https:\/\/swisstrans.info\/it\/2024\/05\/03\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\/","og_site_name":"Swisstrans","article_published_time":"2024-05-03T14:33:33+00:00","og_image":[{"width":2414,"height":1564,"url":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2025\/12\/VNL_3.5.24_2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/swisstrans.info\/it\/2024\/05\/03\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\/#article","isPartOf":{"@id":"https:\/\/swisstrans.info\/it\/2024\/05\/03\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\/"},"author":{"name":"","@id":""},"headline":"Il forum della logistica del VNL affronta i mondi del lavoro in cambiamento","datePublished":"2024-05-03T14:33:33+00:00","mainEntityOfPage":{"@id":"https:\/\/swisstrans.info\/it\/2024\/05\/03\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\/"},"wordCount":508,"commentCount":0,"publisher":{"@id":"https:\/\/swisstrans.info\/it\/#organization"},"image":{"@id":"https:\/\/swisstrans.info\/it\/2024\/05\/03\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\/#primaryimage"},"thumbnailUrl":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2025\/12\/VNL_3.5.24_2.jpg","articleSection":["Schweiz","Svizzera","Switzerland"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/swisstrans.info\/it\/2024\/05\/03\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/swisstrans.info\/it\/2024\/05\/03\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\/","url":"https:\/\/swisstrans.info\/it\/2024\/05\/03\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\/","name":"-","isPartOf":{"@id":"https:\/\/swisstrans.info\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/swisstrans.info\/it\/2024\/05\/03\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\/#primaryimage"},"image":{"@id":"https:\/\/swisstrans.info\/it\/2024\/05\/03\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\/#primaryimage"},"thumbnailUrl":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2025\/12\/VNL_3.5.24_2.jpg","datePublished":"2024-05-03T14:33:33+00:00","breadcrumb":{"@id":"https:\/\/swisstrans.info\/it\/2024\/05\/03\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swisstrans.info\/it\/2024\/05\/03\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/swisstrans.info\/it\/2024\/05\/03\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\/#primaryimage","url":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2025\/12\/VNL_3.5.24_2.jpg","contentUrl":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2025\/12\/VNL_3.5.24_2.jpg","width":2414,"height":1564},{"@type":"BreadcrumbList","@id":"https:\/\/swisstrans.info\/it\/2024\/05\/03\/il-forum-della-logistica-del-vnl-affronta-i-mondi-del-lavoro-in-cambiamento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/swisstrans.info\/it\/"},{"@type":"ListItem","position":2,"name":"Il forum della logistica del VNL affronta i mondi del lavoro in cambiamento"}]},{"@type":"WebSite","@id":"https:\/\/swisstrans.info\/it\/#website","url":"https:\/\/swisstrans.info\/it\/","name":"Swisstrans","description":"Swisstrans \u00e8 una piattaforma informativa per il trasporto e la logistica in Svizzera, attiva dal 2002, che mette in contatto spedizionieri e fornitori di prodotti e servizi.","publisher":{"@id":"https:\/\/swisstrans.info\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swisstrans.info\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/swisstrans.info\/it\/#organization","name":"Logismedia Group AG","alternateName":"Logismedia Group AG","url":"https:\/\/swisstrans.info\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/swisstrans.info\/it\/#\/schema\/logo\/image\/","url":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2026\/01\/swisstrans_logo.png","contentUrl":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2026\/01\/swisstrans_logo.png","width":823,"height":164,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/swisstrans.info\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/showcase\/swisstrans-info\/"]}]}},"_links":{"self":[{"href":"https:\/\/swisstrans.info\/it\/wp-json\/wp\/v2\/posts\/65132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swisstrans.info\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/swisstrans.info\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/swisstrans.info\/it\/wp-json\/wp\/v2\/comments?post=65132"}],"version-history":[{"count":0,"href":"https:\/\/swisstrans.info\/it\/wp-json\/wp\/v2\/posts\/65132\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swisstrans.info\/it\/wp-json\/wp\/v2\/media\/6580"}],"wp:attachment":[{"href":"https:\/\/swisstrans.info\/it\/wp-json\/wp\/v2\/media?parent=65132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/swisstrans.info\/it\/wp-json\/wp\/v2\/categories?post=65132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/swisstrans.info\/it\/wp-json\/wp\/v2\/tags?post=65132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}