{"id":98547,"date":"2022-05-10T15:08:50","date_gmt":"2022-05-10T13:08:50","guid":{"rendered":"https:\/\/swisstrans.brand-architecture.at\/?p=98547"},"modified":"2026-02-04T10:51:23","modified_gmt":"2026-02-04T09:51:23","slug":"dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel","status":"publish","type":"post","link":"https:\/\/swisstrans.info\/pt-pt\/2022\/05\/10\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\/","title":{"rendered":"Dr. Hansj\u00f6rg Rodi nomeado para a dire\u00e7\u00e3o da K\u00fchne+Nagel"},"content":{"rendered":"<h5><strong>O Conselho de Administra\u00e7\u00e3o da K\u00fchne + Nagel International AG nomeou Dr. Hansj\u00f6rg Rodi para a sua dire\u00e7\u00e3o a partir de 1 de agosto de 2022. Hansj\u00f6rg Rodi assumir\u00e1 a responsabilidade pela \u00e1rea de transportes terrestres, sucedendo a Stefan Paul, que, ao mesmo tempo, se tornar\u00e1 o novo Chief Executive Officer do grupo K\u00fchne+Nagel.<\/strong><\/h5>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-19139 alignleft\" src=\"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2026\/02\/Kuehne_Nagel_10.5.22.jpg_2-300x275.jpg\" alt=\"\" width=\"199\" height=\"183\" \/>(Schindellegi) Hansj\u00f6rg Rodi, nascido em 1966, est\u00e1 na K\u00fchne+Nagel desde 2016 em fun\u00e7\u00f5es de lideran\u00e7a, mais recentemente como respons\u00e1vel pela regi\u00e3o Europa, com quase 44.000 colaboradores. Ele est\u00e1 ativo na ind\u00fastria da log\u00edstica h\u00e1 mais de 25 anos em v\u00e1rias posi\u00e7\u00f5es de lideran\u00e7a. Rodi estudou Economia e obteve o doutoramento na Universidade de Vestf\u00e1lia em M\u00fcnster.<\/p>\n<p>Com um volume de neg\u00f3cios l\u00edquido de CHF 3,7 mil milh\u00f5es em 2021 e cerca de 9.700 colaboradores, a \u00e1rea de transportes terrestres da K\u00fchne+Nagel \u00e9 um dos principais fornecedores a n\u00edvel mundial. Os clientes da K\u00fchne+Nagel beneficiam de m\u00e1xima flexibilidade e qualidade de servi\u00e7o para as suas cargas fracionadas, completas (FTL) ou parciais (LTL). Em 2021, a \u00e1rea processou 24,4 milh\u00f5es de envios.<\/p>\n<h5><strong>Jens Drewes assume a Regi\u00e3o Europa<\/strong><\/h5>\n<p>Como sucessor de Hansj\u00f6rg Rodi na Regi\u00e3o Europa, foi designado Jens Drewes (nascido em 1969). Jens Drewes est\u00e1 em fun\u00e7\u00f5es de lideran\u00e7a na K\u00fchne+Nagel na \u00c1sia desde 1997, sendo respons\u00e1vel pela regi\u00e3o \u00c1sia-Pac\u00edfico desde 2013.<\/p>\n<p>Fotos: \u00a9 K\u00fchne + Nagel<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Conselho de Administra\u00e7\u00e3o da K\u00fchne + Nagel International AG nomeou Dr. Hansj\u00f6rg Rodi para a sua dire\u00e7\u00e3o a partir de 1 de agosto de 2022.<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":95776,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6690,6364,6689],"tags":[],"class_list":["post-98547","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahn-binnenschifffahrt-strasse","category-schweiz","category-logistik-spedition"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Swisstrans - Dr. Hansj\u00f6rg Rodi nomeado para a dire\u00e7\u00e3o da K\u00fchne+Nagel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swisstrans.info\/pt-pt\/2022\/05\/10\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Swisstrans - Dr. Hansj\u00f6rg Rodi nomeado para a dire\u00e7\u00e3o da K\u00fchne+Nagel\" \/>\n<meta property=\"og:description\" content=\"O Conselho de Administra\u00e7\u00e3o da K\u00fchne + Nagel International AG nomeou Dr. Hansj\u00f6rg Rodi para a sua dire\u00e7\u00e3o a partir de 1 de agosto de 2022. [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swisstrans.info\/pt-pt\/2022\/05\/10\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\/\" \/>\n<meta property=\"og:site_name\" content=\"Swisstrans\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-10T13:08:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-04T09:51:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2026\/02\/Kuehne_Nagel_10.5.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1532\" \/>\n\t<meta property=\"og:image:height\" content=\"778\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Danny Fritz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Danny Fritz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/2022\\\/05\\\/10\\\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/2022\\\/05\\\/10\\\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\\\/\"},\"author\":{\"name\":\"Danny Fritz\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/#\\\/schema\\\/person\\\/0b7f2287f9870b00f71d6988a755c876\"},\"headline\":\"Dr. Hansj\u00f6rg Rodi nomeado para a dire\u00e7\u00e3o da K\u00fchne+Nagel\",\"datePublished\":\"2022-05-10T13:08:50+00:00\",\"dateModified\":\"2026-02-04T09:51:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/2022\\\/05\\\/10\\\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\\\/\"},\"wordCount\":258,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/2022\\\/05\\\/10\\\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/swisstrans.info\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/02\\\/Kuehne_Nagel_10.5.22.jpg\",\"articleSection\":[\"Intermodal \\\/ Stra\u00dfe\",\"Schweiz\",\"Spedition &amp; Logistik\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/2022\\\/05\\\/10\\\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/2022\\\/05\\\/10\\\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\\\/\",\"url\":\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/2022\\\/05\\\/10\\\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\\\/\",\"name\":\"Swisstrans - Dr. Hansj\u00f6rg Rodi nomeado para a dire\u00e7\u00e3o da K\u00fchne+Nagel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/2022\\\/05\\\/10\\\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/2022\\\/05\\\/10\\\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/swisstrans.info\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/02\\\/Kuehne_Nagel_10.5.22.jpg\",\"datePublished\":\"2022-05-10T13:08:50+00:00\",\"dateModified\":\"2026-02-04T09:51:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/2022\\\/05\\\/10\\\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/2022\\\/05\\\/10\\\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/2022\\\/05\\\/10\\\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/swisstrans.info\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/02\\\/Kuehne_Nagel_10.5.22.jpg\",\"contentUrl\":\"https:\\\/\\\/swisstrans.info\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/02\\\/Kuehne_Nagel_10.5.22.jpg\",\"width\":1532,\"height\":778},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/2022\\\/05\\\/10\\\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dr. Hansj\u00f6rg Rodi nomeado para a dire\u00e7\u00e3o da K\u00fchne+Nagel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/\",\"name\":\"Swisstrans\",\"description\":\"A Swisstrans \u00e9 uma plataforma de informa\u00e7\u00e3o para transporte e log\u00edstica na Su\u00ed\u00e7a, existente desde 2002, que liga expedidores a fornecedores de produtos e servi\u00e7os.\",\"publisher\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"alternateName\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swisstrans.info\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/01\\\/swisstrans_logo.png\",\"contentUrl\":\"https:\\\/\\\/swisstrans.info\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/01\\\/swisstrans_logo.png\",\"width\":823,\"height\":164,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/swisstrans-info\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/#\\\/schema\\\/person\\\/0b7f2287f9870b00f71d6988a755c876\",\"name\":\"Danny Fritz\",\"sameAs\":[\"https:\\\/\\\/dashboard.brand-architecture.at\"],\"url\":\"https:\\\/\\\/swisstrans.info\\\/pt-pt\\\/author\\\/danny\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Swisstrans - Dr. Hansj\u00f6rg Rodi nomeado para a dire\u00e7\u00e3o da K\u00fchne+Nagel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swisstrans.info\/pt-pt\/2022\/05\/10\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\/","og_locale":"pt_PT","og_type":"article","og_title":"Swisstrans - Dr. Hansj\u00f6rg Rodi nomeado para a dire\u00e7\u00e3o da K\u00fchne+Nagel","og_description":"O Conselho de Administra\u00e7\u00e3o da K\u00fchne + Nagel International AG nomeou Dr. Hansj\u00f6rg Rodi para a sua dire\u00e7\u00e3o a partir de 1 de agosto de 2022. [\u2026]","og_url":"https:\/\/swisstrans.info\/pt-pt\/2022\/05\/10\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\/","og_site_name":"Swisstrans","article_published_time":"2022-05-10T13:08:50+00:00","article_modified_time":"2026-02-04T09:51:23+00:00","og_image":[{"width":1532,"height":778,"url":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2026\/02\/Kuehne_Nagel_10.5.22.jpg","type":"image\/jpeg"}],"author":"Danny Fritz","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Danny Fritz","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/swisstrans.info\/pt-pt\/2022\/05\/10\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\/#article","isPartOf":{"@id":"https:\/\/swisstrans.info\/pt-pt\/2022\/05\/10\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\/"},"author":{"name":"Danny Fritz","@id":"https:\/\/swisstrans.info\/pt-pt\/#\/schema\/person\/0b7f2287f9870b00f71d6988a755c876"},"headline":"Dr. Hansj\u00f6rg Rodi nomeado para a dire\u00e7\u00e3o da K\u00fchne+Nagel","datePublished":"2022-05-10T13:08:50+00:00","dateModified":"2026-02-04T09:51:23+00:00","mainEntityOfPage":{"@id":"https:\/\/swisstrans.info\/pt-pt\/2022\/05\/10\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\/"},"wordCount":258,"commentCount":0,"publisher":{"@id":"https:\/\/swisstrans.info\/pt-pt\/#organization"},"image":{"@id":"https:\/\/swisstrans.info\/pt-pt\/2022\/05\/10\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\/#primaryimage"},"thumbnailUrl":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2026\/02\/Kuehne_Nagel_10.5.22.jpg","articleSection":["Intermodal \/ Stra\u00dfe","Schweiz","Spedition &amp; Logistik"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/swisstrans.info\/pt-pt\/2022\/05\/10\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/swisstrans.info\/pt-pt\/2022\/05\/10\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\/","url":"https:\/\/swisstrans.info\/pt-pt\/2022\/05\/10\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\/","name":"Swisstrans - Dr. Hansj\u00f6rg Rodi nomeado para a dire\u00e7\u00e3o da K\u00fchne+Nagel","isPartOf":{"@id":"https:\/\/swisstrans.info\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/swisstrans.info\/pt-pt\/2022\/05\/10\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\/#primaryimage"},"image":{"@id":"https:\/\/swisstrans.info\/pt-pt\/2022\/05\/10\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\/#primaryimage"},"thumbnailUrl":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2026\/02\/Kuehne_Nagel_10.5.22.jpg","datePublished":"2022-05-10T13:08:50+00:00","dateModified":"2026-02-04T09:51:23+00:00","breadcrumb":{"@id":"https:\/\/swisstrans.info\/pt-pt\/2022\/05\/10\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swisstrans.info\/pt-pt\/2022\/05\/10\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/swisstrans.info\/pt-pt\/2022\/05\/10\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\/#primaryimage","url":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2026\/02\/Kuehne_Nagel_10.5.22.jpg","contentUrl":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2026\/02\/Kuehne_Nagel_10.5.22.jpg","width":1532,"height":778},{"@type":"BreadcrumbList","@id":"https:\/\/swisstrans.info\/pt-pt\/2022\/05\/10\/dr-hansjoerg-rodi-nomeado-para-a-direcao-da-kuehnenagel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/swisstrans.info\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Dr. Hansj\u00f6rg Rodi nomeado para a dire\u00e7\u00e3o da K\u00fchne+Nagel"}]},{"@type":"WebSite","@id":"https:\/\/swisstrans.info\/pt-pt\/#website","url":"https:\/\/swisstrans.info\/pt-pt\/","name":"Swisstrans","description":"A Swisstrans \u00e9 uma plataforma de informa\u00e7\u00e3o para transporte e log\u00edstica na Su\u00ed\u00e7a, existente desde 2002, que liga expedidores a fornecedores de produtos e servi\u00e7os.","publisher":{"@id":"https:\/\/swisstrans.info\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swisstrans.info\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/swisstrans.info\/pt-pt\/#organization","name":"Logismedia Group AG","alternateName":"Logismedia Group AG","url":"https:\/\/swisstrans.info\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/swisstrans.info\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2026\/01\/swisstrans_logo.png","contentUrl":"https:\/\/swisstrans.info\/wp-content\/uploads\/sites\/8\/2026\/01\/swisstrans_logo.png","width":823,"height":164,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/swisstrans.info\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/showcase\/swisstrans-info\/"]},{"@type":"Person","@id":"https:\/\/swisstrans.info\/pt-pt\/#\/schema\/person\/0b7f2287f9870b00f71d6988a755c876","name":"Danny Fritz","sameAs":["https:\/\/dashboard.brand-architecture.at"],"url":"https:\/\/swisstrans.info\/pt-pt\/author\/danny\/"}]}},"_links":{"self":[{"href":"https:\/\/swisstrans.info\/pt-pt\/wp-json\/wp\/v2\/posts\/98547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swisstrans.info\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/swisstrans.info\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/swisstrans.info\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/swisstrans.info\/pt-pt\/wp-json\/wp\/v2\/comments?post=98547"}],"version-history":[{"count":2,"href":"https:\/\/swisstrans.info\/pt-pt\/wp-json\/wp\/v2\/posts\/98547\/revisions"}],"predecessor-version":[{"id":98549,"href":"https:\/\/swisstrans.info\/pt-pt\/wp-json\/wp\/v2\/posts\/98547\/revisions\/98549"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swisstrans.info\/pt-pt\/wp-json\/wp\/v2\/media\/95776"}],"wp:attachment":[{"href":"https:\/\/swisstrans.info\/pt-pt\/wp-json\/wp\/v2\/media?parent=98547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/swisstrans.info\/pt-pt\/wp-json\/wp\/v2\/categories?post=98547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/swisstrans.info\/pt-pt\/wp-json\/wp\/v2\/tags?post=98547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}